{"id":1819,"date":"2018-12-03T13:45:07","date_gmt":"2018-12-03T13:45:07","guid":{"rendered":"http:\/\/sw-themes.com\/porto_dummy\/?page_id=1819"},"modified":"2019-08-20T11:01:33","modified_gmt":"2019-08-20T14:01:33","slug":"servicos","status":"publish","type":"page","link":"https:\/\/gamatel.com.br\/en\/servicos\/","title":{"rendered":"Our services"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row top-row vc_custom_1543845513575 porto-inner-container wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div class=\"porto-wrap-container container\"><div class=\"row\"><div class=\"vc_column_container col-md-12 col-lg-4\" data-appear-animation=\"fadeInLeft\"><div class=\"wpb_wrapper vc_column-inner\"><a class=\"porto-sicon-box-link\" href=\"http:\/\/gamatel.com.br\/radiocomunicacao\/\" target='_blank'><div class=\"porto-sicon-box  wpb_custom_1efe903570d178ff0a9b7bfa5febd3a4 style_1 left-icon\"><div class=\"porto-sicon-left\"><div class=\"porto-just-icon-wrapper porto-icon advanced\" style=\"color:#1e80be;width:35px;height:35px;line-height:35px;border-radius:500px;font-size:27px;\"><i class=\"fas fa-arrow-alt-circle-down\"><\/i><\/div><\/div><div class=\"porto-sicon-body\"><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-weight:700;line-height:15px;\">Aparelhos de radiocomunica\u00e7\u00e3o<\/h3><\/div> <!-- header --><div class=\"porto-sicon-description\" style=\"\">Loca\u00e7\u00e3o, venda e manuten\u00e7\u00e3o de equipamentos de radiocomunica\u00e7\u00e3o.<\/div> <!-- description --><\/div><\/div><!-- porto-sicon-box --><\/a><\/div><\/div><div class=\"vc_column_container col-md-12 col-lg-4\" data-appear-animation=\"fadeInLeft\" data-appear-animation-delay=\"200\"><div class=\"wpb_wrapper vc_column-inner\"><a class=\"porto-sicon-box-link\" href=\"https:\/\/gamatel.com.br\/telefonia\/#aparelhos-telefonicos\"><div class=\"porto-sicon-box  wpb_custom_1efe903570d178ff0a9b7bfa5febd3a4 style_1 left-icon\"><div class=\"porto-sicon-left\"><div class=\"porto-just-icon-wrapper porto-icon advanced\" style=\"color:#1e80be;width:35px;height:35px;line-height:35px;border-radius:500px;font-size:27px;\"><i class=\"fas fa-headset\"><\/i><\/div><\/div><div class=\"porto-sicon-body\"><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-weight:700;line-height:15px;\">Solu\u00e7\u00f5es de Telefonia IP<\/h3><\/div> <!-- header --><div class=\"porto-sicon-description\" style=\"\">Solu\u00e7\u00f5es de telefonia de \u00faltima gera\u00e7\u00e3o e acess\u00f3rios em geral.<\/div> <!-- description --><\/div><\/div><!-- porto-sicon-box --><\/a><\/div><\/div><div class=\"vc_column_container col-md-12 col-lg-4\" data-appear-animation=\"fadeInLeft\" data-appear-animation-delay=\"400\"><div class=\"wpb_wrapper vc_column-inner\"><a class=\"porto-sicon-box-link\" href=\"https:\/\/gamatel.com.br\/telefonia\/#central-pabx\"><div class=\"porto-sicon-box  wpb_custom_1efe903570d178ff0a9b7bfa5febd3a4 style_1 left-icon\"><div class=\"porto-sicon-left\"><div class=\"porto-just-icon-wrapper porto-icon advanced\" style=\"color:#1e80be;width:35px;height:35px;line-height:35px;border-radius:500px;font-size:27px;\"><i class=\"fas fa-project-diagram\"><\/i><\/div><\/div><div class=\"porto-sicon-body\"><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-weight:700;line-height:15px;\">PABX Inteligente<\/h3><\/div> <!-- header --><div class=\"porto-sicon-description\" style=\"\">Venda, instala\u00e7\u00e3o e manuten\u00e7\u00e3o para redes PABX com fio ou sem fio.<\/div> <!-- description --><\/div><\/div><!-- porto-sicon-box --><\/a><\/div><\/div><div class=\"vc_column_container col-md-12 col-lg-4\" data-appear-animation=\"fadeInRight\" data-appear-animation-delay=\"800\"><div class=\"wpb_wrapper vc_column-inner\"><a class=\"porto-sicon-box-link\" href=\"https:\/\/gamatel.com.br\/seguranca\/#cameras-de-seguranca\"><div class=\"porto-sicon-box  wpb_custom_1efe903570d178ff0a9b7bfa5febd3a4 style_1 left-icon\"><div class=\"porto-sicon-left\"><div class=\"porto-just-icon-wrapper porto-icon advanced\" style=\"color:#1e80be;width:35px;height:35px;line-height:35px;border-radius:500px;font-size:27px;\"><i class=\"fas fa-video\"><\/i><\/div><\/div><div class=\"porto-sicon-body\"><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-weight:700;line-height:15px;\">C\u00e2meras de Monitoramento<\/h3><\/div> <!-- header --><div class=\"porto-sicon-description\" style=\"\">Venda e instala\u00e7\u00e3o de c\u00e2meras de seguran\u00e7a com monitoramento wifi 24hrs.<\/div> <!-- description --><\/div><\/div><!-- porto-sicon-box --><\/a><\/div><\/div><div class=\"vc_column_container col-md-12 col-lg-4\" data-appear-animation=\"fadeInRight\" data-appear-animation-delay=\"600\"><div class=\"wpb_wrapper vc_column-inner\"><a class=\"porto-sicon-box-link\" href=\"https:\/\/gamatel.com.br\/seguranca\/#central-de-alarme\"><div class=\"porto-sicon-box  wpb_custom_1efe903570d178ff0a9b7bfa5febd3a4 style_1 left-icon\"><div class=\"porto-sicon-left\"><div class=\"porto-just-icon-wrapper porto-icon advanced\" style=\"color:#1e80be;width:35px;height:35px;line-height:35px;border-radius:500px;font-size:27px;\"><i class=\"fas fa-user-secret\"><\/i><\/div><\/div><div class=\"porto-sicon-body\"><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-weight:700;line-height:15px;\">Central de Alarme<\/h3><\/div> <!-- header --><div class=\"porto-sicon-description\" style=\"\">Venda e instala\u00e7\u00e3o de centrais de alarme para a sua seguran\u00e7a.<\/div> <!-- description --><\/div><\/div><!-- porto-sicon-box --><\/a><\/div><\/div><div class=\"vc_column_container col-md-12 col-lg-4\" data-appear-animation=\"fadeInRight\" data-appear-animation-delay=\"400\"><div class=\"wpb_wrapper vc_column-inner\"><a class=\"porto-sicon-box-link\" href=\"https:\/\/gamatel.com.br\/energia\/\"><div class=\"porto-sicon-box  wpb_custom_1efe903570d178ff0a9b7bfa5febd3a4 style_1 left-icon\"><div class=\"porto-sicon-left\"><div class=\"porto-just-icon-wrapper porto-icon advanced\" style=\"color:#1e80be;width:35px;height:35px;line-height:35px;border-radius:500px;font-size:27px;\"><i class=\"fas fa-sun\"><\/i><\/div><\/div><div class=\"porto-sicon-body\"><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-weight:700;line-height:15px;\">Pain\u00e9is Solares<\/h3><\/div> <!-- header --><div class=\"porto-sicon-description\" style=\"\">Venda e instala\u00e7\u00e3o de pain\u00e9is solares.<\/div> <!-- description --><\/div><\/div><!-- porto-sicon-box --><\/a><\/div><\/div><div class=\"vc_column_container col-md-12 col-lg-4\" data-appear-animation=\"fadeInLeft\" data-appear-animation-delay=\"800\"><div class=\"wpb_wrapper vc_column-inner\"><\/div><\/div><div class=\"vc_column_container col-md-12 col-lg-4\" data-appear-animation=\"fadeInLeft\" data-appear-animation-delay=\"1000\"><div class=\"wpb_wrapper vc_column-inner\"><\/div><\/div><div class=\"vc_column_container col-md-12 col-lg-4\" data-appear-animation=\"fadeInLeft\" data-appear-animation-delay=\"1200\"><div class=\"wpb_wrapper vc_column-inner\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row row top-row vc_custom_1543849261012 vc_row-has-fill wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div data-vc-parallax=\"2\" data-vc-parallax-image=\"https:\/\/gamatel.com.br\/wp-content\/uploads\/2019\/04\/Sem-T\u00edtulo-3.jpg\" class=\"vc_column_container col-md-6 vc_general vc_parallax vc_parallax-content-moving vc_custom_1556227937048\"><div class=\"wpb_wrapper vc_column-inner\"><\/div><\/div><div class=\"col-half-section pl-3 pr-3 pl-md-5 pr-md-0 vc_column_container col-md-6 vc_custom_1543849481443\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"porto-u-heading mb-1  wpb_custom_95aa9a11c17ad45cfabaf210d84ee7cc porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0 \" data-appear-animation=\"maskUp\"><div class=\"porto-u-main-heading\"><h4   style=\"font-weight:700;\">O que h\u00e1 de mais moderno em Radiocomunica\u00e7\u00e3o para a sua empresa<\/h4><\/div><style>.porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0.porto-u-heading{text-align:left}<\/style><\/div>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp font-size-sm wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p>Comunica\u00e7\u00f5es seguras e confi\u00e1veis s\u00e3o essenciais nos ambientes extremos, seja com o supervisor de mina trabalhando debaixo da terra ou com o trabalhador petroqu\u00edmico efetuando a manuten\u00e7\u00e3o de uma tubula\u00e7\u00e3o ou mesmo em uma floresta.<\/p>\n<p>Os r\u00e1dios port\u00e1teis linha MOTOTRBO\u2122 mant\u00e9m seus trabalhadores conectados, seguros e produtivos, onde quer que trabalhem. Nosso \u00e1udio, melhor em sua categoria, e as insuper\u00e1veis capacidades de dados mais do que nunca conferem poder \u00e0s pessoas.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<div class=\"vc_btn3-container vc_btn3-center vc_do_btn\" >\r\n\t<a class=\"vc_btn3 vc_btn3-shape-default wpb_custom_6687b26f39488ddbb85ddb3c1ce8e111 btn btn-lg btn-primary\" href=\"http:\/\/gamatel.com.br\/radiocomunicacao\/\" title=\"\">Saiba Mais<\/a>\t<\/div>\r\n<\/div><\/div><\/div><div class=\"vc_row wpb_row row top-row vc_custom_1543849261012 vc_row-has-fill wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div data-vc-parallax=\"2\" data-vc-parallax-image=\"https:\/\/gamatel.com.br\/wp-content\/uploads\/2019\/04\/Unified-Service-Desk-para-Call-Center-767x511@2x-1.jpg\" class=\"order-md-2 vc_column_container col-md-6 vc_general vc_parallax vc_parallax-content-moving vc_custom_1554992344528\"><div class=\"wpb_wrapper vc_column-inner\"><\/div><\/div><div class=\"vc_column_container col-md-6 vc_custom_1543849756478\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"vc_row wpb_row vc_inner row col-half-section col-half-section-right no-padding\"><div class=\"vc_column_container col-md-12\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"porto-u-heading mb-1  wpb_custom_95aa9a11c17ad45cfabaf210d84ee7cc porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0 \" data-appear-animation=\"maskUp\"><div class=\"porto-u-main-heading\"><h4   style=\"font-weight:700;\">Solu\u00e7\u00f5es de Telefonia IP<\/h4><\/div><style>.porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0.porto-u-heading{text-align:left}<\/style><\/div>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp font-size-sm wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p>Conhe\u00e7a os produtos perfeitos para sua empresa ter uma comunica\u00e7\u00e3o eficiente, flex\u00edvel e de qualidade. Com uma solu\u00e7\u00e3o IP completa, al\u00e9m de aproveitar os benef\u00edcios das centrais existentes, gateways internet (e rede local) e telefones VoIP, voc\u00ea pode cuidar de tudo com c\u00e2meras IP, junto com os demais equipamentos de sua rede local (e WAN) com as solu\u00e7\u00f5es ofertadas pela Gamatel.<\/p>\n<p>A linha de c\u00e2meras Intelbras Multi HD \u00e9 4 em 1. Com ela, seu projeto ganha multi-possibilidades. Voc\u00ea pode instalar e monitorar com a tecnologia de sua escolha: Intelbras HDCVI, AHD, HDTVI e anal\u00f3gica. Al\u00e9m disso, ela tem diversas intelig\u00eancias para profissionalizar ainda mais seu projeto. A linha Multi HD \u00e9 o primeiro passo para o futuro da seguran\u00e7a.<\/p>\n<p><b>\u00a0* IP (Internet <\/b><b>Protocol<\/b><b>) <\/b><\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<div class=\"porto-u-heading mb-1  wpb_custom_95aa9a11c17ad45cfabaf210d84ee7cc porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0 \" data-appear-animation=\"maskUp\"><div class=\"porto-u-main-heading\"><h4   style=\"font-weight:700;\">Solu\u00e7\u00f5es para call center<\/h4><\/div><style>.porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0.porto-u-heading{text-align:left}<\/style><\/div>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp font-size-sm wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p>Para simplificar o trabalho e oferecer mais efici\u00eancia para empresas de call center, a Gamatel oferta telefones corporativos, telefones IP, headsets de qualidade, gravador e todos os acess\u00f3rios necess\u00e1rios.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<div class=\"vc_btn3-container vc_btn3-center vc_do_btn\" >\r\n\t<a class=\"vc_btn3 vc_btn3-shape-default wpb_custom_6687b26f39488ddbb85ddb3c1ce8e111 btn btn-lg btn-primary\" href=\"http:\/\/gamatel.com.br\/telefonia\/\" title=\"\">Saiba Mais<\/a>\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row row top-row vc_custom_1543849261012 vc_row-has-fill wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div data-vc-parallax=\"2\" data-vc-parallax-image=\"https:\/\/gamatel.com.br\/wp-content\/uploads\/2019\/04\/IMG_0542.jpg\" class=\"vc_column_container col-md-6 vc_general vc_parallax vc_parallax-content-moving vc_custom_1554992048283\"><div class=\"wpb_wrapper vc_column-inner\"><\/div><\/div><div class=\"col-half-section pl-3 pr-3 pl-md-5 pr-md-0 vc_column_container col-md-6 vc_custom_1543849481443\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"porto-u-heading mb-1  wpb_custom_95aa9a11c17ad45cfabaf210d84ee7cc porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0 \" data-appear-animation=\"maskUp\"><div class=\"porto-u-main-heading\"><h4   style=\"font-weight:700;\">C\u00e2meras IP<\/h4><\/div><style>.porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0.porto-u-heading{text-align:left}<\/style><\/div>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp font-size-sm wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p><span style=\"text-align: justify;\">As c\u00e2meras IP s\u00e3o o futuro do monitoramento. Elas oferecem a melhor qualidade de imagens com intelig\u00eancias que v\u00e3o te surpreender. E, ao contr\u00e1rio do que todo mundo pensa, elas n\u00e3o s\u00e3o complicadas para instalar e configurar. Com s\u00e9ries acess\u00edveis ou superprofissionais, as c\u00e2meras IP oferecem solu\u00e7\u00f5es que v\u00e3o deixar seu projeto de monitoramento muito mais eficiente e com mais seguran\u00e7a.<\/span><\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<div class=\"porto-u-heading mb-1  wpb_custom_95aa9a11c17ad45cfabaf210d84ee7cc porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0 \" data-appear-animation=\"maskUp\"><div class=\"porto-u-main-heading\"><h4   style=\"font-weight:700;\">C\u00e2meras Wi-Fi<\/h4><\/div><style>.porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0.porto-u-heading{text-align:left}<\/style><\/div>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp font-size-sm wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p>A tranquilidade que faltava, dentro ou fora de casa. A <b>linha <\/b><b>Mibo<\/b> foi desenvolvida para que voc\u00ea tenha o poder de cuidar da pr\u00f3pria seguran\u00e7a. Todo o controle necess\u00e1rio estar\u00e1 em suas m\u00e3os de qualquer lugar atrav\u00e9s de seu smartphone, desde a instala\u00e7\u00e3o e grava\u00e7\u00e3o at\u00e9 o recebimento de notifica\u00e7\u00f5es por movimento.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<div class=\"porto-u-heading mb-1  wpb_custom_95aa9a11c17ad45cfabaf210d84ee7cc porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0 \" data-appear-animation=\"maskUp\"><div class=\"porto-u-main-heading\"><h4   style=\"font-weight:700;\">C\u00e2meras Multi HD<\/h4><\/div><style>.porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0.porto-u-heading{text-align:left}<\/style><\/div>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp font-size-sm wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p>A linha de c\u00e2meras Intelbras Multi HD \u00e9 4 em 1. Com ela, seu projeto ganha multi-possibilidades. Voc\u00ea pode instalar e monitorar com a tecnologia de sua escolha: Intelbras HDCVI, AHD, HDTVI e anal\u00f3gica. Al\u00e9m disso, ela tem diversas intelig\u00eancias para profissionalizar ainda mais seu projeto. A linha Multi HD \u00e9 o primeiro passo para o futuro da seguran\u00e7a.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<div class=\"vc_btn3-container vc_btn3-center vc_do_btn\" >\r\n\t<a class=\"vc_btn3 vc_btn3-shape-default wpb_custom_6687b26f39488ddbb85ddb3c1ce8e111 btn btn-lg btn-primary\" href=\"http:\/\/gamatel.com.br\/seguranca\/\" title=\"Seguran\u00e7a\">Saiba Mais<\/a>\t<\/div>\r\n<\/div><\/div><\/div><div class=\"vc_row wpb_row row top-row vc_custom_1543849261012 vc_row-has-fill wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div data-vc-parallax=\"2\" data-vc-parallax-image=\"https:\/\/gamatel.com.br\/wp-content\/uploads\/2019\/04\/entendendo-os-sistemas-de-alarme-1.png\" class=\"order-md-2 vc_column_container col-md-6 vc_general vc_parallax vc_parallax-content-moving vc_custom_1554991808703\"><div class=\"wpb_wrapper vc_column-inner\"><\/div><\/div><div class=\"vc_column_container col-md-6 vc_custom_1543849756478\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"vc_row wpb_row vc_inner row col-half-section col-half-section-right no-padding\"><div class=\"vc_column_container col-md-12\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"porto-u-heading mb-1  wpb_custom_95aa9a11c17ad45cfabaf210d84ee7cc porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0 \" data-appear-animation=\"maskUp\"><div class=\"porto-u-main-heading\"><h4   style=\"font-weight:700;\">Mais seguran\u00e7a para o seu neg\u00f3cio<\/h4><\/div><style>.porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0.porto-u-heading{text-align:left}<\/style><\/div>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp font-size-sm wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p>Proteja seus funcion\u00e1rios e patrim\u00f4nio com as nossas solu\u00e7\u00f5es em seguran\u00e7a. S\u00e3o sistemas de c\u00e2mera, alarme, detec\u00e7\u00e3o de inc\u00eandio e controle de acesso para evitar preju\u00edzos \u00e0 sua empresa.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<div class=\"vc_btn3-container vc_btn3-center vc_do_btn\" >\r\n\t<a class=\"vc_btn3 vc_btn3-shape-default wpb_custom_6687b26f39488ddbb85ddb3c1ce8e111 btn btn-lg btn-primary\" href=\"http:\/\/gamatel.com.br\/seguranca\/\" title=\"Seguran\u00e7a\">Saiba Mais<\/a>\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row row top-row vc_custom_1543849261012 vc_row-has-fill wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div data-vc-parallax=\"2\" data-vc-parallax-image=\"https:\/\/gamatel.com.br\/wp-content\/uploads\/2019\/04\/Solar-Panels.jpg\" class=\"vc_column_container col-md-6 vc_general vc_parallax vc_parallax-content-moving vc_custom_1554990521355\"><div class=\"wpb_wrapper vc_column-inner\"><\/div><\/div><div class=\"col-half-section pl-3 pr-3 pl-md-5 pr-md-0 vc_column_container col-md-6 vc_custom_1543849481443\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"porto-u-heading mb-1  wpb_custom_95aa9a11c17ad45cfabaf210d84ee7cc porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0 \" data-appear-animation=\"maskUp\"><div class=\"porto-u-main-heading\"><h4   style=\"font-weight:700;\">Economia e sustentabilidade para a sua casa<\/h4><\/div><style>.porto-u-ad87e2eaf3f9c495180fe0156ddf3eb0.porto-u-heading{text-align:left}<\/style><\/div>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp font-size-sm wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p><span style=\"text-align: justify;\">Mais economia, autonomia e prote\u00e7\u00e3o para seus dispositivos e energia sustent\u00e1vel para a sua casa. Oferecemos uma linha completa de energia, para voc\u00ea ter luz onde estiver e ainda economizar na conta.<\/span><\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<div class=\"vc_btn3-container vc_btn3-center vc_do_btn\" >\r\n\t<a class=\"vc_btn3 vc_btn3-shape-default wpb_custom_6687b26f39488ddbb85ddb3c1ce8e111 btn btn-lg btn-primary\" href=\"http:\/\/gamatel.com.br\/energia\/\" title=\"Energia\">Saiba Mais<\/a>\t<\/div>\r\n<\/div><\/div><\/div><div class=\"vc_row wpb_row top-row vc_custom_1566308660624 section section-parallax mt-0 mb-0 section-no-borders porto-inner-container wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div class=\"porto-wrap-container container\"><div class=\"row\"><div class=\"vc_column_container col-md-12\"><div class=\"wpb_wrapper vc_column-inner\"><div class=\"vc_empty_space\"   style=\"height: 80px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><h2 style=\"color: #111111;text-align: center\" class=\"vc_custom_heading vc_do_custom_heading m-t-lg m-b-none wpb_custom_aa365bd5046e8294520b4e73732b9d15\" ><strong>Ofertas<\/strong> Sob Medida<\/h2><p style=\"color: #111111;text-align: center\" class=\"vc_custom_heading vc_do_custom_heading vc_custom_1555037151590 wpb_custom_aa365bd5046e8294520b4e73732b9d15\" >Escolha aqui a melhor oferta para seu neg\u00f3cio.<\/p><div id=\"porto-products-9e0c4dee1f2f2fd12506a77038e0d92c\" class=\"porto-products wpb_content_element onhover wpb_custom_38b889397c293c9f42c8a8d3db66c106\"><div class=\"woocommerce columns-3 \"><ul class=\"products products-container grid show-nav-middle pcols-lg-3 pcols-md-3 pcols-xs-2 pcols-ls-1 pwidth-lg-3 pwidth-md-3 pwidth-xs-2 pwidth-ls-1 is-shortcode\"\r\n\t data-product_layout=\"product-default show-links-hover\">\r\n\r\n<li class=\"product-col product-default show-links-hover product type-product post-4082 status-publish first onbackorder product_cat-pabx product_cat-telefonia product_tag-pabx-em-nuvem product_tag-pabx-ip product_tag-pabx-virtual product_tag-telefone-sip product_tag-telefonia has-post-thumbnail sale featured virtual purchasable product-type-simple\">\r\n<div class=\"product-inner\">\r\n\t\r\n\t<div class=\"product-image\">\r\n\r\n\t\t<a  href=\"https:\/\/gamatel.com.br\/en\/product\/https-gamatel-com-br-telefonia\/\" aria-label=\"product\">\r\n\t\t\t<div class=\"labels\"><div class=\"onhot\">Hot<\/div><div class=\"onsale\">-36%<\/div><\/div><div data-link=\"https:\/\/gamatel.com.br\/en\/carro-de-compras\/\" class=\"viewcart viewcart-4082\" title=\"View cart\"><\/div><div class=\"inner img-effect\"><img loading=\"lazy\" decoding=\"async\" width=\"367\" height=\"367\" src=\"https:\/\/gamatel.com.br\/wp-content\/uploads\/2026\/03\/CallCenter-VoiceSystems-Gamatel-V2-367x367.png\" class=\"attachment-member size-member\" alt=\"RAMAL PABX VIRTUAL IP VOICE SYSTEMS GAMATEL\" \/><img loading=\"lazy\" decoding=\"async\" width=\"367\" height=\"367\" src=\"https:\/\/gamatel.com.br\/wp-content\/uploads\/2026\/03\/Telefone-FANVIL-V62PRO-fone-bluetooth-fig-2-367x367.png\" class=\"hover-image\" alt=\"\" \/><\/div>\t\t<\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"product-content\">\r\n\t\t<span class=\"category-list\"><a href=\"https:\/\/gamatel.com.br\/en\/categoria\/pabx\/\" rel=\"tag\">PABX<\/a>, <a href=\"https:\/\/gamatel.com.br\/en\/categoria\/telefonia\/\" rel=\"tag\">Telefonia<\/a><\/span>\r\n\t\t\t<a class=\"product-loop-title\"  href=\"https:\/\/gamatel.com.br\/en\/product\/https-gamatel-com-br-telefonia\/\">\r\n\t<h3 class=\"woocommerce-loop-product__title\">RAMAL PABX VIRTUAL IP VOICE SYSTEMS GAMATEL<\/h3>\t<\/a>\r\n\t\r\n\t\t\r\n\r\n<div class=\"rating-wrap\">\r\n\t<div class=\"rating-content\"><div class=\"star-rating\" title=\"0\"><span style=\"width:0%\"><strong class=\"rating\">0<\/strong> out of 5<\/span><\/div><\/div>\r\n<\/div>\r\n\r\n\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#82;&#36;<\/span>45,00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Original price was: &#082;&#036;45,00.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#82;&#36;<\/span>28,90<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Current price is: &#082;&#036;28,90.<\/span><\/span>\n\r\n\t\t<div class=\"add-links-wrap\">\r\n\t<div class=\"add-links clearfix\">\r\n\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1819?add-to-cart=4082\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4082\" data-quantity=\"1\" class=\"viewcart-style-1 button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"4082\" data-product_sku=\"Ramais\" aria-label=\"Add to cart: &ldquo;RAMAL PABX VIRTUAL IP VOICE SYSTEMS GAMATEL&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;RAMAL PABX VIRTUAL IP VOICE SYSTEMS GAMATEL&rdquo; has been added to your cart\">Add to cart<\/a>\t\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4082\" class=\"screen-reader-text\">\r\n\t\t\t<\/span>\r\n\t\t<div class=\"quickview\" data-id=\"4082\" title=\"Quick View\">Quick View<\/div>\t<\/div>\r\n\t<\/div>\r\n\t\t\t<input type=\"hidden\" class=\"pmwProductId\" data-id=\"4082\">\n\t\t\t\t\t<script>\n\t\t\t(window.pmwDataLayer = window.pmwDataLayer || {}).products                = window.pmwDataLayer.products || {};\n\t\t\twindow.pmwDataLayer.products[4082] = {\"id\":\"4082\",\"sku\":\"Ramais\",\"price\":28.9,\"brand\":\"\",\"quantity\":1,\"dyn_r_ids\":{\"post_id\":\"4082\",\"sku\":\"Ramais\",\"gpf\":\"woocommerce_gpf_4082\",\"gla\":\"gla_4082\"},\"is_variable\":false,\"type\":\"simple\",\"name\":\"RAMAL PABX VIRTUAL IP VOICE SYSTEMS GAMATEL\",\"category\":[\"PABX\",\"Telefonia\"],\"is_variation\":false};\n\t\t\t\t\twindow.pmw_product_position = window.pmw_product_position || 1;\n\t\twindow.pmwDataLayer.products[4082]['position'] = window.pmw_product_position++;\n\t\t\t\t<\/script>\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n<\/li>\r\n\r\n<li class=\"product-col product-default show-links-hover product type-product post-4391 status-publish onbackorder product_cat-pabx product_cat-telefonia product_tag-pabx-em-nuvem product_tag-pabx-ip product_tag-pabx-virtual product_tag-telefone-sip product_tag-telefonia has-post-thumbnail sale featured virtual purchasable product-type-simple\">\r\n<div class=\"product-inner\">\r\n\t\r\n\t<div class=\"product-image\">\r\n\r\n\t\t<a  href=\"https:\/\/gamatel.com.br\/en\/product\/pacote-30-ramais-pabx-virtual-ip-voice-systems-gamatel\/\" aria-label=\"product\">\r\n\t\t\t<div class=\"labels\"><div class=\"onhot\">Hot<\/div><div class=\"onsale\">-15%<\/div><\/div><div data-link=\"https:\/\/gamatel.com.br\/en\/carro-de-compras\/\" class=\"viewcart viewcart-4391\" title=\"View cart\"><\/div><div class=\"inner img-effect\"><img loading=\"lazy\" decoding=\"async\" width=\"367\" height=\"367\" src=\"https:\/\/gamatel.com.br\/wp-content\/uploads\/2026\/03\/CallCenter-VoiceSystems-Gamatel-V2-367x367.png\" class=\"attachment-member size-member\" alt=\"PACOTE 30 RAMAIS - PABX VIRTUAL IP VOICE SYSTEMS GAMATEL\" \/><img loading=\"lazy\" decoding=\"async\" width=\"367\" height=\"367\" src=\"https:\/\/gamatel.com.br\/wp-content\/uploads\/2026\/03\/Telefone-FANVIL-V62PRO-fone-bluetooth-fig-2-367x367.png\" class=\"hover-image\" alt=\"\" \/><\/div>\t\t<\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"product-content\">\r\n\t\t<span class=\"category-list\"><a href=\"https:\/\/gamatel.com.br\/en\/categoria\/pabx\/\" rel=\"tag\">PABX<\/a>, <a href=\"https:\/\/gamatel.com.br\/en\/categoria\/telefonia\/\" rel=\"tag\">Telefonia<\/a><\/span>\r\n\t\t\t<a class=\"product-loop-title\"  href=\"https:\/\/gamatel.com.br\/en\/product\/pacote-30-ramais-pabx-virtual-ip-voice-systems-gamatel\/\">\r\n\t<h3 class=\"woocommerce-loop-product__title\">PACOTE 30 RAMAIS &#8211; PABX VIRTUAL IP VOICE SYSTEMS GAMATEL<\/h3>\t<\/a>\r\n\t\r\n\t\t\r\n\r\n<div class=\"rating-wrap\">\r\n\t<div class=\"rating-content\"><div class=\"star-rating\" title=\"0\"><span style=\"width:0%\"><strong class=\"rating\">0<\/strong> out of 5<\/span><\/div><\/div>\r\n<\/div>\r\n\r\n\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#82;&#36;<\/span>810,00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Original price was: &#082;&#036;810,00.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#82;&#36;<\/span>690,00<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Current price is: &#082;&#036;690,00.<\/span><\/span>\n\r\n\t\t<div class=\"add-links-wrap\">\r\n\t<div class=\"add-links clearfix\">\r\n\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1819?add-to-cart=4391\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4391\" data-quantity=\"1\" class=\"viewcart-style-1 button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"4391\" data-product_sku=\"Loca\u00e7\u00e3o\" aria-label=\"Add to cart: &ldquo;PACOTE 30 RAMAIS - PABX VIRTUAL IP VOICE SYSTEMS GAMATEL&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;PACOTE 30 RAMAIS - PABX VIRTUAL IP VOICE SYSTEMS GAMATEL&rdquo; has been added to your cart\">Add to cart<\/a>\t\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4391\" class=\"screen-reader-text\">\r\n\t\t\t<\/span>\r\n\t\t<div class=\"quickview\" data-id=\"4391\" title=\"Quick View\">Quick View<\/div>\t<\/div>\r\n\t<\/div>\r\n\t\t\t<input type=\"hidden\" class=\"pmwProductId\" data-id=\"4391\">\n\t\t\t\t\t<script>\n\t\t\t(window.pmwDataLayer = window.pmwDataLayer || {}).products                = window.pmwDataLayer.products || {};\n\t\t\twindow.pmwDataLayer.products[4391] = {\"id\":\"4391\",\"sku\":\"Loca\u00e7\u00e3o\",\"price\":690,\"brand\":\"\",\"quantity\":1,\"dyn_r_ids\":{\"post_id\":\"4391\",\"sku\":\"Loca\u00e7\u00e3o\",\"gpf\":\"woocommerce_gpf_4391\",\"gla\":\"gla_4391\"},\"is_variable\":false,\"type\":\"simple\",\"name\":\"PACOTE 30 RAMAIS - PABX VIRTUAL IP VOICE SYSTEMS GAMATEL\",\"category\":[\"PABX\",\"Telefonia\"],\"is_variation\":false};\n\t\t\t\t\twindow.pmw_product_position = window.pmw_product_position || 1;\n\t\twindow.pmwDataLayer.products[4391]['position'] = window.pmw_product_position++;\n\t\t\t\t<\/script>\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n<\/li>\r\n\r\n<li class=\"product-col product-default show-links-hover product type-product post-4392 status-publish last onbackorder product_cat-pabx product_cat-telefonia product_tag-pabx-em-nuvem product_tag-pabx-ip product_tag-pabx-virtual product_tag-telefone-sip product_tag-telefonia has-post-thumbnail sale featured virtual purchasable product-type-simple\">\r\n<div class=\"product-inner\">\r\n\t\r\n\t<div class=\"product-image\">\r\n\r\n\t\t<a  href=\"https:\/\/gamatel.com.br\/en\/product\/aparelho-telefone-ip-giga_eth-poe-fanvil-v61g\/\" aria-label=\"product\">\r\n\t\t\t<div class=\"labels\"><div class=\"onhot\">Hot<\/div><div class=\"onsale\">-17%<\/div><\/div><div data-link=\"https:\/\/gamatel.com.br\/en\/carro-de-compras\/\" class=\"viewcart viewcart-4392\" title=\"View cart\"><\/div><div class=\"inner\"><img loading=\"lazy\" decoding=\"async\" width=\"367\" height=\"367\" src=\"https:\/\/gamatel.com.br\/wp-content\/uploads\/2026\/03\/Fanvil-V61G-Telefone-SIP-367x367.jpg\" class=\"attachment-member size-member\" alt=\"LOCA\u00c7\u00c3O APARELHO TELEFONE IP GIGA_ETH - POE - FANVIL V61G\" \/><\/div>\t\t<\/a>\r\n\t\t\t<\/div>\r\n\r\n\t<div class=\"product-content\">\r\n\t\t<span class=\"category-list\"><a href=\"https:\/\/gamatel.com.br\/en\/categoria\/pabx\/\" rel=\"tag\">PABX<\/a>, <a href=\"https:\/\/gamatel.com.br\/en\/categoria\/telefonia\/\" rel=\"tag\">Telefonia<\/a><\/span>\r\n\t\t\t<a class=\"product-loop-title\"  href=\"https:\/\/gamatel.com.br\/en\/product\/aparelho-telefone-ip-giga_eth-poe-fanvil-v61g\/\">\r\n\t<h3 class=\"woocommerce-loop-product__title\">LOCA\u00c7\u00c3O APARELHO TELEFONE IP GIGA_ETH &#8211; POE &#8211; FANVIL V61G<\/h3>\t<\/a>\r\n\t\r\n\t\t\r\n\r\n<div class=\"rating-wrap\">\r\n\t<div class=\"rating-content\"><div class=\"star-rating\" title=\"0\"><span style=\"width:0%\"><strong class=\"rating\">0<\/strong> out of 5<\/span><\/div><\/div>\r\n<\/div>\r\n\r\n\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#82;&#36;<\/span>35,90<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Original price was: &#082;&#036;35,90.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#82;&#36;<\/span>29,90<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Current price is: &#082;&#036;29,90.<\/span><\/span>\n\r\n\t\t<div class=\"add-links-wrap\">\r\n\t<div class=\"add-links clearfix\">\r\n\t\t<a href=\"\/en\/wp-json\/wp\/v2\/pages\/1819?add-to-cart=4392\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4392\" data-quantity=\"1\" class=\"viewcart-style-1 button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"4392\" data-product_sku=\"Loca\u00e7\u00e3o Mensal\" aria-label=\"Add to cart: &ldquo;LOCA\u00c7\u00c3O APARELHO TELEFONE IP GIGA_ETH - POE - FANVIL V61G&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;LOCA\u00c7\u00c3O APARELHO TELEFONE IP GIGA_ETH - POE - FANVIL V61G&rdquo; has been added to your cart\">Add to cart<\/a>\t\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4392\" class=\"screen-reader-text\">\r\n\t\t\t<\/span>\r\n\t\t<div class=\"quickview\" data-id=\"4392\" title=\"Quick View\">Quick View<\/div>\t<\/div>\r\n\t<\/div>\r\n\t\t\t<input type=\"hidden\" class=\"pmwProductId\" data-id=\"4392\">\n\t\t\t\t\t<script>\n\t\t\t(window.pmwDataLayer = window.pmwDataLayer || {}).products                = window.pmwDataLayer.products || {};\n\t\t\twindow.pmwDataLayer.products[4392] = {\"id\":\"4392\",\"sku\":\"Loca\u00e7\u00e3o Mensal\",\"price\":29.9,\"brand\":\"\",\"quantity\":1,\"dyn_r_ids\":{\"post_id\":\"4392\",\"sku\":\"Loca\u00e7\u00e3o Mensal\",\"gpf\":\"woocommerce_gpf_4392\",\"gla\":\"gla_4392\"},\"is_variable\":false,\"type\":\"simple\",\"name\":\"LOCA\u00c7\u00c3O APARELHO TELEFONE IP GIGA_ETH - POE - FANVIL V61G\",\"category\":[\"PABX\",\"Telefonia\"],\"is_variation\":false};\n\t\t\t\t\twindow.pmw_product_position = window.pmw_product_position || 1;\n\t\twindow.pmwDataLayer.products[4392]['position'] = window.pmw_product_position++;\n\t\t\t\t<\/script>\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n<\/li>\r\n<\/ul>\r\n<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 80px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Aparelhos de radiocomunica\u00e7\u00e3o Loca\u00e7\u00e3o, venda e manuten\u00e7\u00e3o de equipamentos de radiocomunica\u00e7\u00e3o. Solu\u00e7\u00f5es de Telefonia IP Solu\u00e7\u00f5es de telefonia de \u00faltima gera\u00e7\u00e3o e acess\u00f3rios em geral. PABX Inteligente Venda, instala\u00e7\u00e3o e manuten\u00e7\u00e3o para redes PABX com fio ou sem fio. C\u00e2meras de Monitoramento Venda e instala\u00e7\u00e3o de c\u00e2meras de seguran\u00e7a com monitoramento wifi 24hrs. Central de [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-1819","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Aparelhos de radiocomunica\u00e7\u00e3o Loca\u00e7\u00e3o, venda e manuten\u00e7\u00e3o de equipamentos de radiocomunica\u00e7\u00e3o. Solu\u00e7\u00f5es de Telefonia IP Solu\u00e7\u00f5es de telefonia de \u00faltima gera\u00e7\u00e3o e acess\u00f3rios em geral. PABX Inteligente Venda, instala\u00e7\u00e3o e manuten\u00e7\u00e3o para redes PABX com fio ou sem fio. C\u00e2meras de Monitoramento Venda e instala\u00e7\u00e3o de c\u00e2meras de seguran\u00e7a com monitoramento wifi 24hrs. Central de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/gamatel.com.br\/en\/servicos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gamatel | Tecnologia em Comunica\u00e7\u00f5es - Tecnologia em Comunica\u00e7\u00f5es, l\u00edder em tecnologias de comunica\u00e7\u00f5es.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Nossos Servi\u00e7os - Gamatel | Tecnologia em Comunica\u00e7\u00f5es\" \/>\n\t\t<meta property=\"og:description\" content=\"Aparelhos de radiocomunica\u00e7\u00e3o Loca\u00e7\u00e3o, venda e manuten\u00e7\u00e3o de equipamentos de radiocomunica\u00e7\u00e3o. Solu\u00e7\u00f5es de Telefonia IP Solu\u00e7\u00f5es de telefonia de \u00faltima gera\u00e7\u00e3o e acess\u00f3rios em geral. PABX Inteligente Venda, instala\u00e7\u00e3o e manuten\u00e7\u00e3o para redes PABX com fio ou sem fio. C\u00e2meras de Monitoramento Venda e instala\u00e7\u00e3o de c\u00e2meras de seguran\u00e7a com monitoramento wifi 24hrs. Central de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/gamatel.com.br\/en\/servicos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-12-03T13:45:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-08-20T14:01:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Nossos Servi\u00e7os - Gamatel | Tecnologia em Comunica\u00e7\u00f5es\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Aparelhos de radiocomunica\u00e7\u00e3o Loca\u00e7\u00e3o, venda e manuten\u00e7\u00e3o de equipamentos de radiocomunica\u00e7\u00e3o. Solu\u00e7\u00f5es de Telefonia IP Solu\u00e7\u00f5es de telefonia de \u00faltima gera\u00e7\u00e3o e acess\u00f3rios em geral. PABX Inteligente Venda, instala\u00e7\u00e3o e manuten\u00e7\u00e3o para redes PABX com fio ou sem fio. C\u00e2meras de Monitoramento Venda e instala\u00e7\u00e3o de c\u00e2meras de seguran\u00e7a com monitoramento wifi 24hrs. Central de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/servicos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gamatel.com.br\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/servicos\\\/#listItem\",\"name\":\"Nossos Servi\\u00e7os\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/servicos\\\/#listItem\",\"position\":2,\"name\":\"Nossos Servi\\u00e7os\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/#organization\",\"name\":\"Gamatel | Tecnologia em Comunica\\u00e7\\u00f5es\",\"description\":\"Tecnologia em Comunica\\u00e7\\u00f5es, l\\u00edder em tecnologias de comunica\\u00e7\\u00f5es.\",\"url\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/servicos\\\/#webpage\",\"url\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/servicos\\\/\",\"name\":\"Nossos Servi\\u00e7os - Gamatel | Tecnologia em Comunica\\u00e7\\u00f5es\",\"description\":\"Aparelhos de radiocomunica\\u00e7\\u00e3o Loca\\u00e7\\u00e3o, venda e manuten\\u00e7\\u00e3o de equipamentos de radiocomunica\\u00e7\\u00e3o. Solu\\u00e7\\u00f5es de Telefonia IP Solu\\u00e7\\u00f5es de telefonia de \\u00faltima gera\\u00e7\\u00e3o e acess\\u00f3rios em geral. PABX Inteligente Venda, instala\\u00e7\\u00e3o e manuten\\u00e7\\u00e3o para redes PABX com fio ou sem fio. C\\u00e2meras de Monitoramento Venda e instala\\u00e7\\u00e3o de c\\u00e2meras de seguran\\u00e7a com monitoramento wifi 24hrs. Central de\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/servicos\\\/#breadcrumblist\"},\"datePublished\":\"2018-12-03T13:45:07-03:00\",\"dateModified\":\"2019-08-20T11:01:33-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/\",\"name\":\"Gamatel | Tecnologia em Comunica\\u00e7\\u00f5es\",\"description\":\"Tecnologia em Comunica\\u00e7\\u00f5es, l\\u00edder em tecnologias de comunica\\u00e7\\u00f5es.\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Nossos Servi\u00e7os - Gamatel | Tecnologia em Comunica\u00e7\u00f5es","description":"Aparelhos de radiocomunica\u00e7\u00e3o Loca\u00e7\u00e3o, venda e manuten\u00e7\u00e3o de equipamentos de radiocomunica\u00e7\u00e3o. Solu\u00e7\u00f5es de Telefonia IP Solu\u00e7\u00f5es de telefonia de \u00faltima gera\u00e7\u00e3o e acess\u00f3rios em geral. PABX Inteligente Venda, instala\u00e7\u00e3o e manuten\u00e7\u00e3o para redes PABX com fio ou sem fio. C\u00e2meras de Monitoramento Venda e instala\u00e7\u00e3o de c\u00e2meras de seguran\u00e7a com monitoramento wifi 24hrs. Central de","canonical_url":"https:\/\/gamatel.com.br\/en\/servicos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/gamatel.com.br\/en\/servicos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gamatel.com.br\/en#listItem","position":1,"name":"Home","item":"https:\/\/gamatel.com.br\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/gamatel.com.br\/en\/servicos\/#listItem","name":"Nossos Servi\u00e7os"}},{"@type":"ListItem","@id":"https:\/\/gamatel.com.br\/en\/servicos\/#listItem","position":2,"name":"Nossos Servi\u00e7os","previousItem":{"@type":"ListItem","@id":"https:\/\/gamatel.com.br\/en#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/gamatel.com.br\/en\/#organization","name":"Gamatel | Tecnologia em Comunica\u00e7\u00f5es","description":"Tecnologia em Comunica\u00e7\u00f5es, l\u00edder em tecnologias de comunica\u00e7\u00f5es.","url":"https:\/\/gamatel.com.br\/en\/"},{"@type":"WebPage","@id":"https:\/\/gamatel.com.br\/en\/servicos\/#webpage","url":"https:\/\/gamatel.com.br\/en\/servicos\/","name":"Nossos Servi\u00e7os - Gamatel | Tecnologia em Comunica\u00e7\u00f5es","description":"Aparelhos de radiocomunica\u00e7\u00e3o Loca\u00e7\u00e3o, venda e manuten\u00e7\u00e3o de equipamentos de radiocomunica\u00e7\u00e3o. Solu\u00e7\u00f5es de Telefonia IP Solu\u00e7\u00f5es de telefonia de \u00faltima gera\u00e7\u00e3o e acess\u00f3rios em geral. PABX Inteligente Venda, instala\u00e7\u00e3o e manuten\u00e7\u00e3o para redes PABX com fio ou sem fio. C\u00e2meras de Monitoramento Venda e instala\u00e7\u00e3o de c\u00e2meras de seguran\u00e7a com monitoramento wifi 24hrs. Central de","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/gamatel.com.br\/en\/#website"},"breadcrumb":{"@id":"https:\/\/gamatel.com.br\/en\/servicos\/#breadcrumblist"},"datePublished":"2018-12-03T13:45:07-03:00","dateModified":"2019-08-20T11:01:33-03:00"},{"@type":"WebSite","@id":"https:\/\/gamatel.com.br\/en\/#website","url":"https:\/\/gamatel.com.br\/en\/","name":"Gamatel | Tecnologia em Comunica\u00e7\u00f5es","description":"Tecnologia em Comunica\u00e7\u00f5es, l\u00edder em tecnologias de comunica\u00e7\u00f5es.","inLanguage":"en-US","publisher":{"@id":"https:\/\/gamatel.com.br\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Gamatel | Tecnologia em Comunica\u00e7\u00f5es - Tecnologia em Comunica\u00e7\u00f5es, l\u00edder em tecnologias de comunica\u00e7\u00f5es.","og:type":"article","og:title":"Nossos Servi\u00e7os - Gamatel | Tecnologia em Comunica\u00e7\u00f5es","og:description":"Aparelhos de radiocomunica\u00e7\u00e3o Loca\u00e7\u00e3o, venda e manuten\u00e7\u00e3o de equipamentos de radiocomunica\u00e7\u00e3o. Solu\u00e7\u00f5es de Telefonia IP Solu\u00e7\u00f5es de telefonia de \u00faltima gera\u00e7\u00e3o e acess\u00f3rios em geral. PABX Inteligente Venda, instala\u00e7\u00e3o e manuten\u00e7\u00e3o para redes PABX com fio ou sem fio. C\u00e2meras de Monitoramento Venda e instala\u00e7\u00e3o de c\u00e2meras de seguran\u00e7a com monitoramento wifi 24hrs. Central de","og:url":"https:\/\/gamatel.com.br\/en\/servicos\/","article:published_time":"2018-12-03T13:45:07+00:00","article:modified_time":"2019-08-20T14:01:33+00:00","twitter:card":"summary_large_image","twitter:title":"Nossos Servi\u00e7os - Gamatel | Tecnologia em Comunica\u00e7\u00f5es","twitter:description":"Aparelhos de radiocomunica\u00e7\u00e3o Loca\u00e7\u00e3o, venda e manuten\u00e7\u00e3o de equipamentos de radiocomunica\u00e7\u00e3o. Solu\u00e7\u00f5es de Telefonia IP Solu\u00e7\u00f5es de telefonia de \u00faltima gera\u00e7\u00e3o e acess\u00f3rios em geral. PABX Inteligente Venda, instala\u00e7\u00e3o e manuten\u00e7\u00e3o para redes PABX com fio ou sem fio. C\u00e2meras de Monitoramento Venda e instala\u00e7\u00e3o de c\u00e2meras de seguran\u00e7a com monitoramento wifi 24hrs. Central de"},"aioseo_meta_data":{"post_id":"1819","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-11 17:51:50","updated":"2025-09-01 19:16:48","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gamatel.com.br\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNossos Servi\u00e7os\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/gamatel.com.br\/en"},{"label":"Nossos Servi\u00e7os","link":"https:\/\/gamatel.com.br\/en\/servicos\/"}],"_links":{"self":[{"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/pages\/1819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/comments?post=1819"}],"version-history":[{"count":44,"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/pages\/1819\/revisions"}],"predecessor-version":[{"id":3712,"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/pages\/1819\/revisions\/3712"}],"wp:attachment":[{"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/media?parent=1819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}