{"id":75,"date":"2016-06-14T06:36:54","date_gmt":"2016-06-14T06:36:54","guid":{"rendered":"http:\/\/sw-themes.com\/porto_dummy\/?page_id=75"},"modified":"2022-02-09T17:59:17","modified_gmt":"2022-02-09T20:59:17","slug":"contato","status":"publish","type":"page","link":"https:\/\/gamatel.com.br\/en\/contato\/","title":{"rendered":"Contact"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row top-row m-b-xl vc_custom_1644440301013 porto-inner-container wpb_custom_034b39d9bc6c6b310d69e39f0ccf274f\"><div class=\"porto-wrap-container container\"><div class=\"row\"><div class=\"vc_column_container col-md-6 text-left\"><div class=\"wpb_wrapper vc_column-inner\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4127-o1\" lang=\"pt-BR\" dir=\"ltr\" data-wpcf7-id=\"4127\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/75#wpcf7-f4127-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rios de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/75#wpcf7-f4127-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4127\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_BR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4127-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<label> <strong> <blue>  <\/blue> <\/strong> <\/label>\n\n<label> <strong> <blue> ENVIE SUA MENSAGEM ! <\/blue> <\/strong> <\/label>\n\n<label> Seu nome (obrigat\u00f3rio)\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n\n<label> Seu e-mail (obrigat\u00f3rio)\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n\n<label> Seu Telefone (obrigat\u00f3rio)\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"tel-726\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-726\" \/><\/span> <\/label>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox-654\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required wpcf7-exclusive-checkbox\"><span class=\"wpcf7-list-item first\"><input type=\"checkbox\" name=\"checkbox-654\" value=\"Radiocomunica\u00e7\u00e3o\" \/><span class=\"wpcf7-list-item-label\">Radio comunication<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"checkbox-654\" value=\"Telefonia\" \/><span class=\"wpcf7-list-item-label\">Telephony<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"checkbox-654\" value=\"Seguran\u00e7a\" \/><span class=\"wpcf7-list-item-label\">Safety<\/span><\/span><span class=\"wpcf7-list-item last\"><input type=\"checkbox\" name=\"checkbox-654\" value=\"Energia Solar\" \/><span class=\"wpcf7-list-item-label\">Energia Solar<\/span><\/span><\/span><\/span>\n\n<label> Subject matter\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n\n<label> Sua mensagem\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>\u0394<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"91\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/div><\/div><div class=\"vc_column_container col-md-6\"><div class=\"wpb_wrapper vc_column-inner\"><h4 style=\"color: #111111\" class=\"vc_custom_heading vc_do_custom_heading m-t wpb_custom_aa365bd5046e8294520b4e73732b9d15 align-left heading-primary\" >Enter in<strong>Contact<\/strong><\/h4>\r\n\t<div class=\"wpb_text_column wpb_content_element wpb_custom_7c91d232724f73626cc933bd95b25ff0\" >\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p>To always stay ahead, your workforce must have reliable communications. Let us help you take your communications further.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<div class=\"porto-separator\"><hr class=\"separator-line  wpb_content_element align_center\" style=\"background-image: -webkit-linear-gradient(left, transparent, #EBEBEB, transparent); background-image: linear-gradient(to right, transparent, #EBEBEB, transparent);\"><\/div><h4 style=\"color: #111111\" class=\"vc_custom_heading vc_do_custom_heading wpb_custom_aa365bd5046e8294520b4e73732b9d15 align-left heading-primary\" >Gamatel <strong>Holy Spirit<\/strong><\/h4><div class=\"porto-sicon-box  wpb_custom_991192e517ba80822b25b68bbbc51b14 style_1 default-icon\"><div class=\"porto-sicon-default\"><div class=\"porto-just-icon-wrapper porto-icon circle\" style=\"color:#ffffff;background:#145680;font-size:14px;\"><i class=\"fas fa-map-marker-alt\"><\/i><\/div><\/div><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-size:14px;\"><strong>Address:<\/strong> St. Rita of Cassia, 390 - Lourdes- ZIP Code: 29042-753 Vit\u00f3ria \/ ES<\/h3><\/div> <!-- header --><\/div><!-- porto-sicon-box --><div class=\"porto-sicon-box  wpb_custom_991192e517ba80822b25b68bbbc51b14 style_1 default-icon\"><div class=\"porto-sicon-default\"><div class=\"porto-just-icon-wrapper porto-icon circle\" style=\"color:#ffffff;background:#145680;font-size:14px;\"><i class=\"fas fa-envelope\"><\/i><\/div><\/div><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-size:14px;\"><strong>Email:<\/strong> comercial@gamatel.com.br<\/h3><\/div> <!-- header --><\/div><!-- porto-sicon-box --><div class=\"porto-sicon-box  wpb_custom_991192e517ba80822b25b68bbbc51b14 style_1 default-icon\"><div class=\"porto-sicon-default\"><div class=\"porto-just-icon-wrapper porto-icon circle\" style=\"color:#ffffff;background:#145680;font-size:14px;\"><i class=\"fas fa-phone\"><\/i><\/div><\/div><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-size:14px;\"><strong>Telephone:<\/strong> (27) 4009-4399<\/h3><\/div> <!-- header --><\/div><!-- porto-sicon-box --><div class=\"porto-separator\"><hr class=\"separator-line  wpb_content_element align_center\" style=\"background-image: -webkit-linear-gradient(left, transparent, #EBEBEB, transparent); background-image: linear-gradient(to right, transparent, #EBEBEB, transparent);\"><\/div><h4 style=\"color: #111111\" class=\"vc_custom_heading vc_do_custom_heading wpb_custom_aa365bd5046e8294520b4e73732b9d15 align-left heading-primary\" >Gamatel <strong>Minas Gerais<\/strong><\/h4><div class=\"porto-sicon-box  wpb_custom_991192e517ba80822b25b68bbbc51b14 style_1 default-icon\"><div class=\"porto-sicon-default\"><div class=\"porto-just-icon-wrapper porto-icon circle\" style=\"color:#ffffff;background:#145680;font-size:14px;\"><i class=\"fas fa-map-marker-alt\"><\/i><\/div><\/div><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-size:14px;\"><strong>Address:<\/strong> Av. Brasil, 2472 - Downtown. ZIP Code: 35020-070 Gov. Valadares \/ MG<\/h3><\/div> <!-- header --><\/div><!-- porto-sicon-box --><div class=\"porto-sicon-box  wpb_custom_991192e517ba80822b25b68bbbc51b14 style_1 default-icon\"><div class=\"porto-sicon-default\"><div class=\"porto-just-icon-wrapper porto-icon circle\" style=\"color:#ffffff;background:#145680;font-size:14px;\"><i class=\"fas fa-envelope\"><\/i><\/div><\/div><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-size:14px;\"><strong>Email:<\/strong> gamatel.mg@gamatel.com.br<\/h3><\/div> <!-- header --><\/div><!-- porto-sicon-box --><div class=\"porto-sicon-box  wpb_custom_991192e517ba80822b25b68bbbc51b14 style_1 default-icon\"><div class=\"porto-sicon-default\"><div class=\"porto-just-icon-wrapper porto-icon circle\" style=\"color:#ffffff;background:#145680;font-size:14px;\"><i class=\"fas fa-phone\"><\/i><\/div><\/div><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-size:14px;\"><strong>Telephone:<\/strong> (33) 2101-1800<\/h3><\/div> <!-- header --><\/div><!-- porto-sicon-box --><div class=\"porto-separator\"><hr class=\"separator-line  wpb_content_element align_center\" style=\"background-image: -webkit-linear-gradient(left, transparent, #EBEBEB, transparent); background-image: linear-gradient(to right, transparent, #EBEBEB, transparent);\"><\/div><h4 style=\"color: #111111\" class=\"vc_custom_heading vc_do_custom_heading wpb_custom_aa365bd5046e8294520b4e73732b9d15 align-left heading-primary\" >Time of <strong>Operation<\/strong><\/h4><div class=\"porto-sicon-box  wpb_custom_991192e517ba80822b25b68bbbc51b14 style_1 default-icon\"><div class=\"porto-sicon-default\"><div class=\"porto-just-icon-wrapper porto-icon none\" style=\"color:#000000;font-size:14px;\"><i class=\"far fa-clock\"><\/i><\/div><\/div><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-size:14px;\">Monday - Friday&gt; 8am to 6pm<\/h3><\/div> <!-- header --><\/div><!-- porto-sicon-box --><div class=\"porto-sicon-box  wpb_custom_991192e517ba80822b25b68bbbc51b14 style_1 default-icon\"><div class=\"porto-sicon-default\"><div class=\"porto-just-icon-wrapper porto-icon none\" style=\"font-size:14px;\"><i class=\"far fa-clock\"><\/i><\/div><\/div><div class=\"porto-sicon-header\"><h3 class=\"porto-sicon-title\" style=\"font-size:14px;\">Saturday and Sunday - Closed<\/h3><\/div> <!-- header --><\/div><!-- porto-sicon-box --><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"ENVIE SUA MENSAGEM ! Seu nome (obrigat\u00f3rio) Seu e-mail (obrigat\u00f3rio) Seu Telefone (obrigat\u00f3rio) Radiocomunica\u00e7\u00e3oTelefoniaSeguran\u00e7aEnergia Solar Assunto Sua mensagem &#916; Entre emContato Para manter-se sempre a frente, sua for\u00e7a de trabalho deve ter comunica\u00e7\u00f5es confi\u00e1veis. Deixe nos ajudar voc\u00ea a levar suas comunica\u00e7\u00f5es mais longe. Gamatel Esp\u00edrito SantoEndere\u00e7o: R. Sta. Rita de C\u00e1ssia, 390 - Lourdes- [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-75","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"ENVIE SUA MENSAGEM ! Seu nome (obrigat\u00f3rio) Seu e-mail (obrigat\u00f3rio) Seu Telefone (obrigat\u00f3rio) Radiocomunica\u00e7\u00e3oTelefoniaSeguran\u00e7aEnergia Solar Assunto Sua mensagem \u0394 Entre emContato Para manter-se sempre a frente, sua for\u00e7a de trabalho deve ter comunica\u00e7\u00f5es confi\u00e1veis. Deixe nos ajudar voc\u00ea a levar suas comunica\u00e7\u00f5es mais longe. Gamatel Esp\u00edrito SantoEndere\u00e7o: R. Sta. Rita de C\u00e1ssia, 390 - Lourdes-\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/gamatel.com.br\/en\/contato\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gamatel | Tecnologia em Comunica\u00e7\u00f5es - Tecnologia em Comunica\u00e7\u00f5es, l\u00edder em tecnologias de comunica\u00e7\u00f5es.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Contato - Gamatel | Tecnologia em Comunica\u00e7\u00f5es\" \/>\n\t\t<meta property=\"og:description\" content=\"ENVIE SUA MENSAGEM ! Seu nome (obrigat\u00f3rio) Seu e-mail (obrigat\u00f3rio) Seu Telefone (obrigat\u00f3rio) Radiocomunica\u00e7\u00e3oTelefoniaSeguran\u00e7aEnergia Solar Assunto Sua mensagem \u0394 Entre emContato Para manter-se sempre a frente, sua for\u00e7a de trabalho deve ter comunica\u00e7\u00f5es confi\u00e1veis. Deixe nos ajudar voc\u00ea a levar suas comunica\u00e7\u00f5es mais longe. Gamatel Esp\u00edrito SantoEndere\u00e7o: R. Sta. Rita de C\u00e1ssia, 390 - Lourdes-\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/gamatel.com.br\/en\/contato\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-14T06:36:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-02-09T20:59:17+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Contato - Gamatel | Tecnologia em Comunica\u00e7\u00f5es\" \/>\n\t\t<meta name=\"twitter:description\" content=\"ENVIE SUA MENSAGEM ! Seu nome (obrigat\u00f3rio) Seu e-mail (obrigat\u00f3rio) Seu Telefone (obrigat\u00f3rio) Radiocomunica\u00e7\u00e3oTelefoniaSeguran\u00e7aEnergia Solar Assunto Sua mensagem \u0394 Entre emContato Para manter-se sempre a frente, sua for\u00e7a de trabalho deve ter comunica\u00e7\u00f5es confi\u00e1veis. Deixe nos ajudar voc\u00ea a levar suas comunica\u00e7\u00f5es mais longe. Gamatel Esp\u00edrito SantoEndere\u00e7o: R. Sta. Rita de C\u00e1ssia, 390 - Lourdes-\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/contato\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gamatel.com.br\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/contato\\\/#listItem\",\"name\":\"Contato\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/contato\\\/#listItem\",\"position\":2,\"name\":\"Contato\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/#organization\",\"name\":\"Gamatel | Tecnologia em Comunica\\u00e7\\u00f5es\",\"description\":\"Tecnologia em Comunica\\u00e7\\u00f5es, l\\u00edder em tecnologias de comunica\\u00e7\\u00f5es.\",\"url\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/contato\\\/#webpage\",\"url\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/contato\\\/\",\"name\":\"Contato - Gamatel | Tecnologia em Comunica\\u00e7\\u00f5es\",\"description\":\"ENVIE SUA MENSAGEM ! Seu nome (obrigat\\u00f3rio) Seu e-mail (obrigat\\u00f3rio) Seu Telefone (obrigat\\u00f3rio) Radiocomunica\\u00e7\\u00e3oTelefoniaSeguran\\u00e7aEnergia Solar Assunto Sua mensagem \\u0394 Entre emContato Para manter-se sempre a frente, sua for\\u00e7a de trabalho deve ter comunica\\u00e7\\u00f5es confi\\u00e1veis. Deixe nos ajudar voc\\u00ea a levar suas comunica\\u00e7\\u00f5es mais longe. Gamatel Esp\\u00edrito SantoEndere\\u00e7o: R. Sta. Rita de C\\u00e1ssia, 390 - Lourdes-\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/contato\\\/#breadcrumblist\"},\"datePublished\":\"2016-06-14T06:36:54-03:00\",\"dateModified\":\"2022-02-09T17:59:17-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/\",\"name\":\"Gamatel | Tecnologia em Comunica\\u00e7\\u00f5es\",\"description\":\"Tecnologia em Comunica\\u00e7\\u00f5es, l\\u00edder em tecnologias de comunica\\u00e7\\u00f5es.\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/gamatel.com.br\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Contato - Gamatel | Tecnologia em Comunica\u00e7\u00f5es","description":"ENVIE SUA MENSAGEM ! Seu nome (obrigat\u00f3rio) Seu e-mail (obrigat\u00f3rio) Seu Telefone (obrigat\u00f3rio) Radiocomunica\u00e7\u00e3oTelefoniaSeguran\u00e7aEnergia Solar Assunto Sua mensagem \u0394 Entre emContato Para manter-se sempre a frente, sua for\u00e7a de trabalho deve ter comunica\u00e7\u00f5es confi\u00e1veis. Deixe nos ajudar voc\u00ea a levar suas comunica\u00e7\u00f5es mais longe. Gamatel Esp\u00edrito SantoEndere\u00e7o: R. Sta. Rita de C\u00e1ssia, 390 - Lourdes-","canonical_url":"https:\/\/gamatel.com.br\/en\/contato\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/gamatel.com.br\/en\/contato\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gamatel.com.br\/en#listItem","position":1,"name":"Home","item":"https:\/\/gamatel.com.br\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/gamatel.com.br\/en\/contato\/#listItem","name":"Contato"}},{"@type":"ListItem","@id":"https:\/\/gamatel.com.br\/en\/contato\/#listItem","position":2,"name":"Contato","previousItem":{"@type":"ListItem","@id":"https:\/\/gamatel.com.br\/en#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/gamatel.com.br\/en\/#organization","name":"Gamatel | Tecnologia em Comunica\u00e7\u00f5es","description":"Tecnologia em Comunica\u00e7\u00f5es, l\u00edder em tecnologias de comunica\u00e7\u00f5es.","url":"https:\/\/gamatel.com.br\/en\/"},{"@type":"WebPage","@id":"https:\/\/gamatel.com.br\/en\/contato\/#webpage","url":"https:\/\/gamatel.com.br\/en\/contato\/","name":"Contato - Gamatel | Tecnologia em Comunica\u00e7\u00f5es","description":"ENVIE SUA MENSAGEM ! Seu nome (obrigat\u00f3rio) Seu e-mail (obrigat\u00f3rio) Seu Telefone (obrigat\u00f3rio) Radiocomunica\u00e7\u00e3oTelefoniaSeguran\u00e7aEnergia Solar Assunto Sua mensagem \u0394 Entre emContato Para manter-se sempre a frente, sua for\u00e7a de trabalho deve ter comunica\u00e7\u00f5es confi\u00e1veis. Deixe nos ajudar voc\u00ea a levar suas comunica\u00e7\u00f5es mais longe. Gamatel Esp\u00edrito SantoEndere\u00e7o: R. Sta. Rita de C\u00e1ssia, 390 - Lourdes-","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/gamatel.com.br\/en\/#website"},"breadcrumb":{"@id":"https:\/\/gamatel.com.br\/en\/contato\/#breadcrumblist"},"datePublished":"2016-06-14T06:36:54-03:00","dateModified":"2022-02-09T17:59:17-03:00"},{"@type":"WebSite","@id":"https:\/\/gamatel.com.br\/en\/#website","url":"https:\/\/gamatel.com.br\/en\/","name":"Gamatel | Tecnologia em Comunica\u00e7\u00f5es","description":"Tecnologia em Comunica\u00e7\u00f5es, l\u00edder em tecnologias de comunica\u00e7\u00f5es.","inLanguage":"en-US","publisher":{"@id":"https:\/\/gamatel.com.br\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Gamatel | Tecnologia em Comunica\u00e7\u00f5es - Tecnologia em Comunica\u00e7\u00f5es, l\u00edder em tecnologias de comunica\u00e7\u00f5es.","og:type":"article","og:title":"Contato - Gamatel | Tecnologia em Comunica\u00e7\u00f5es","og:description":"ENVIE SUA MENSAGEM ! Seu nome (obrigat\u00f3rio) Seu e-mail (obrigat\u00f3rio) Seu Telefone (obrigat\u00f3rio) Radiocomunica\u00e7\u00e3oTelefoniaSeguran\u00e7aEnergia Solar Assunto Sua mensagem \u0394 Entre emContato Para manter-se sempre a frente, sua for\u00e7a de trabalho deve ter comunica\u00e7\u00f5es confi\u00e1veis. Deixe nos ajudar voc\u00ea a levar suas comunica\u00e7\u00f5es mais longe. Gamatel Esp\u00edrito SantoEndere\u00e7o: R. Sta. Rita de C\u00e1ssia, 390 - Lourdes-","og:url":"https:\/\/gamatel.com.br\/en\/contato\/","article:published_time":"2016-06-14T06:36:54+00:00","article:modified_time":"2022-02-09T20:59:17+00:00","twitter:card":"summary_large_image","twitter:title":"Contato - Gamatel | Tecnologia em Comunica\u00e7\u00f5es","twitter:description":"ENVIE SUA MENSAGEM ! Seu nome (obrigat\u00f3rio) Seu e-mail (obrigat\u00f3rio) Seu Telefone (obrigat\u00f3rio) Radiocomunica\u00e7\u00e3oTelefoniaSeguran\u00e7aEnergia Solar Assunto Sua mensagem \u0394 Entre emContato Para manter-se sempre a frente, sua for\u00e7a de trabalho deve ter comunica\u00e7\u00f5es confi\u00e1veis. Deixe nos ajudar voc\u00ea a levar suas comunica\u00e7\u00f5es mais longe. Gamatel Esp\u00edrito SantoEndere\u00e7o: R. Sta. Rita de C\u00e1ssia, 390 - Lourdes-"},"aioseo_meta_data":{"post_id":"75","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-11 17:50:30","updated":"2025-09-01 19:16:10","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gamatel.com.br\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tContato\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/gamatel.com.br\/en"},{"label":"Contato","link":"https:\/\/gamatel.com.br\/en\/contato\/"}],"_links":{"self":[{"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/pages\/75","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/comments?post=75"}],"version-history":[{"count":20,"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/pages\/75\/revisions"}],"predecessor-version":[{"id":4135,"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/pages\/75\/revisions\/4135"}],"wp:attachment":[{"href":"https:\/\/gamatel.com.br\/en\/wp-json\/wp\/v2\/media?parent=75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}